{"id":1267,"date":"2024-01-12T07:37:07","date_gmt":"2024-01-12T06:37:07","guid":{"rendered":"https:\/\/moments-botswana.com\/contattateci\/"},"modified":"2026-02-04T07:16:47","modified_gmt":"2026-02-04T06:16:47","slug":"contattateci","status":"publish","type":"page","link":"https:\/\/moments-botswana.com\/it\/contattateci\/","title":{"rendered":"Contattateci"},"content":{"rendered":"<div id=\"pl-1267\"  class=\"panel-layout\" ><div id=\"pg-1267-0\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-widget-style panel-row-style panel-row-style-for-1267-0\" data-stretch-type=\"full-width-stretch\" ><div id=\"pgc-1267-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1267-0-0-0\" class=\"widget_text so-panel widget widget_custom_html panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"textwidget custom-html-widget\"><div id=\"metaslider-id-4757\" style=\"width: 100%;\" class=\"ml-slider-3-107-0 metaslider metaslider-flex metaslider-4757 ml-slider has-carousel-mode ms-theme-blend nav-hidden\" role=\"region\" aria-label=\"Header Kontakt\" data-height=\"400\" data-width=\"600\">\n    <div id=\"metaslider_container_4757\">\n        <div id=\"metaslider_4757\" class=\"flexslider\">\n            <ul class='slides'>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4764 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:44:26\" data-filename=\"IMG_7405-600x400.jpeg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_7405-600x400.jpeg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4764 msDefaultImage\" title=\"Sonnenuntergang Moremi\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4765 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:44:45\" data-filename=\"IMG_8028-600x400.jpeg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8028-600x400.jpeg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4765 msDefaultImage\" title=\"Elefant Chobe Riverfront\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4766 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:45:30\" data-filename=\"IMG_8706-600x400.jpeg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8706-600x400.jpeg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4766 msDefaultImage\" title=\"Sonnenuntergang Khwai\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4767 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:45:40\" data-filename=\"IMG_5173-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_5173-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4767 msDefaultImage\" title=\"L\u00f6we im Gegenlicht\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4768 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:45:50\" data-filename=\"IMG_7358-600x400.jpeg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_7358-600x400.jpeg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4768 msDefaultImage\" title=\"Sternenhimmel Botswana\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4769 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:46:00\" data-filename=\"IMG_8147-600x400.jpeg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8147-600x400.jpeg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4769 msDefaultImage\" title=\"Chobe Riverfront\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4770 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:46:11\" data-filename=\"IMG_9641-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_9641-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4770 msDefaultImage\" title=\"Elefantenfamilie Chobe\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4771 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:46:22\" data-filename=\"IMG_4915-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_4915-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4771 msDefaultImage\" title=\"Gepard\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4772 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:46:32\" data-filename=\"IMG_1294-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_1294-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4772 msDefaultImage\" title=\"Seeadler Chobe Riverfront\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4773 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:46:41\" data-filename=\"IMG_9923-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_9923-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4773 msDefaultImage\" title=\"Kudu M\u00e4nnchen\" \/><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-1267-1\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-widget-style panel-row-style panel-row-style-for-1267-1\" ><div id=\"pgc-1267-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1267-1-0-0\" class=\"so-panel widget widget_sow-headline panel-first-child panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-headline so-widget-sow-headline-default-0ca500063943-1267 so-widget-fittext-wrapper\"\n\t\t\t data-fit-text-compressor=\"0.9\"\n\t\t><div class=\"sow-headline-container \">\n\t\t\t\t\t\t\t<h1 class=\"sow-headline\">\n\t\t\t\t\t\tVenite con noi in un viaggio pieno di bei momenti!\t\t\t\t\t\t<\/h1>\n\t\t\t\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-1267-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1267-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1267-2-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"2\" ><div class=\"panel-widget-style panel-widget-style-for-1267-2-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><a name=\"Contact\"><\/a><\/p>\n<h3>Parliamo del tuo viaggio.<br \/>Saremo lieti di sentirti.<\/h3>\n<\/div>\n<\/div><\/div><\/div><div id=\"panel-1267-2-0-1\" class=\"so-panel widget widget_sow-contact-form\" data-index=\"3\" ><div class=\"panel-widget-style panel-widget-style-for-1267-2-0-1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-contact-form so-widget-sow-contact-form-default-c641b773394b-1267\"\n\t\t\t\n\t\t>\t<form\n\t\taction=\"\/it\/wp-json\/wp\/v2\/pages\/1267\"\n\t\tmethod=\"POST\"\n\t\tclass=\"sow-contact-form\"\n\t\tid=\"contact-form-5213\"\n\t>\n\n\t\t\n\t\t\t\t\t<div class=\"sow-form-field sow-form-field-name\">\n\t\t\t\t<label class=\"sow-form-field-label-above\" for=\"sow-contact-form-field-nome-1\">\n\t\t\t\t<strong>\n\t\t\t\t\tNome\t\t\t\t\t\t\t\t\t<\/strong>\n\t\t\t<\/label>\n\t\t\t\t\t\t\t<div class=\"sow-field-container\">\n\t\t\t\t\t\t\t<input\n\t\t\ttype=\"text\"\n\t\t\tname=\"nome-1\"\n\t\t\tid=\"sow-contact-form-field-nome-1\"\n\t\t\tvalue=\"\"\n\t\t\tclass=\"sow-text-field\"\n\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"sow-form-field sow-form-field-email\">\n\t\t\t\t<label class=\"sow-form-field-label-above\" for=\"sow-contact-form-field-e-mail-1\">\n\t\t\t\t<strong>\n\t\t\t\t\te-mail\t\t\t\t\t\t\t\t\t<\/strong>\n\t\t\t<\/label>\n\t\t\t\t\t\t\t<div class=\"sow-field-container\">\n\t\t\t\t\t\t\t<input\n\t\t\ttype=\"email\"\n\t\t\tname=\"e-mail-1\"\n\t\t\tid=\"sow-contact-form-field-e-mail-1\"\n\t\t\tvalue=\"\"\n\t\t\tclass=\"sow-text-field\"\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"sow-form-field sow-form-field-tel\">\n\t\t\t\t<label class=\"sow-form-field-label-above\" for=\"sow-contact-form-field-numero-di-telefono-1\">\n\t\t\t\t<strong>\n\t\t\t\t\tNumero di telefono\t\t\t\t\t\t\t\t\t<\/strong>\n\t\t\t<\/label>\n\t\t\t\t\t\t\t<div class=\"sow-field-container\">\n\t\t\t\t\t\t\t<input\n\t\t\ttype=\"tel\"\n\t\t\tname=\"numero-di-telefono-1\"\n\t\t\tid=\"sow-contact-form-field-numero-di-telefono-1\"\n\t\t\tvalue=\"\"\n\t\t\tclass=\"sow-text-field\"\t\t\t\t\t\t\t\t\/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"sow-form-field sow-form-field-textarea\">\n\t\t\t\t<label class=\"sow-form-field-label-above\" for=\"sow-contact-form-field-il-vostro-messaggio-per-noi-1\">\n\t\t\t\t<strong>\n\t\t\t\t\tIl vostro messaggio per noi\t\t\t\t\t\t\t\t\t<\/strong>\n\t\t\t<\/label>\n\t\t\t\t\t\t\t<div class=\"sow-field-container\">\n\t\t\t\t\t\t\t<textarea\n\t\t\tname=\"il-vostro-messaggio-per-noi-1\"\n\t\t\tid=\"sow-contact-form-field-il-vostro-messaggio-per-noi-1\"\n\t\t\trows=\"10\"\n\t\t\t\t\t\t\t\t><\/textarea>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<input\n\t\t\t\ttype=\"text\"\n\t\t\t\tname=\"sow-name\"\n\t\t\t\tclass=\"sow-text-field\"\n\t\t\t\tstyle=\"display: none !important; visibility: hidden !important;\"\n\t\t\t\tautocomplete=\"off\"\n\t\t\t\taria-hidden=\"true\"\n\t\t\t>\n\t\t\n\t\t\t\t\t<div class=\"sow-recaptcha\"\n\t\t\t\t\t\t\t\t\tdata-config=\"{&quot;sitekey&quot;:&quot;6Le1Bx4qAAAAABpecEdhRNPequUijAOH3bKE6HHQ&quot;,&quot;theme&quot;:&quot;light&quot;,&quot;type&quot;:&quot;image&quot;,&quot;size&quot;:&quot;normal&quot;}\"\n\t\t\t\t\t\t\t><\/div>\n\t\t\t\n\t\t<div class=\"sow-submit-wrapper \n\t\tsow-submit-styled\t\t\">\n\n\t\t\t<button\n\t\t\t\ttype=\"submit\"\n\t\t\t\tclass=\"sow-submit\n\t\t\t\t\t\t\t\t\"\n\t\t\t\t\t\t\t>\n\t\t\t\tInviare\t\t\t<\/button>\n\t\t<\/div>\n\t\t\t\t<input\n\t\t\ttype=\"hidden\"\n\t\t\tname=\"instance_hash-1\"\n\t\t\tvalue=\"5213612f\"\n\t\t\/>\n\n\t\t<input type=\"hidden\" id=\"_wpnonce\" name=\"_wpnonce\" value=\"1b07d48e61\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/it\/wp-json\/wp\/v2\/pages\/1267\" \/>\t<\/form>\n\t<\/div><\/div><\/div><div id=\"panel-1267-2-0-2\" class=\"widget_text so-panel widget widget_custom_html panel-last-child\" data-index=\"4\" ><div class=\"textwidget custom-html-widget\"><div id=\"metaslider-id-4757\" style=\"width: 100%;\" class=\"ml-slider-3-107-0 metaslider metaslider-flex metaslider-4757 ml-slider has-carousel-mode ms-theme-blend nav-hidden nav-hidden\" role=\"region\" aria-label=\"Header Kontakt\" data-height=\"400\" data-width=\"600\">\n    <div id=\"metaslider_container_4757\">\n        <div id=\"metaslider_4757\" class=\"flexslider\">\n            <ul class='slides'>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4764 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:44:26\" data-filename=\"IMG_7405-600x400.jpeg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_7405-600x400.jpeg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4764 msDefaultImage\" title=\"Sonnenuntergang Moremi\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4765 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:44:45\" data-filename=\"IMG_8028-600x400.jpeg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8028-600x400.jpeg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4765 msDefaultImage\" title=\"Elefant Chobe Riverfront\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4766 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:45:30\" data-filename=\"IMG_8706-600x400.jpeg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8706-600x400.jpeg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4766 msDefaultImage\" title=\"Sonnenuntergang Khwai\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4767 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:45:40\" data-filename=\"IMG_5173-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_5173-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4767 msDefaultImage\" title=\"L\u00f6we im Gegenlicht\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4768 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:45:50\" data-filename=\"IMG_7358-600x400.jpeg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_7358-600x400.jpeg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4768 msDefaultImage\" title=\"Sternenhimmel Botswana\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4769 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:46:00\" data-filename=\"IMG_8147-600x400.jpeg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8147-600x400.jpeg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4769 msDefaultImage\" title=\"Chobe Riverfront\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4770 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:46:11\" data-filename=\"IMG_9641-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_9641-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4770 msDefaultImage\" title=\"Elefantenfamilie Chobe\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4771 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:46:22\" data-filename=\"IMG_4915-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_4915-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4771 msDefaultImage\" title=\"Gepard\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4772 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:46:32\" data-filename=\"IMG_1294-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_1294-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4772 msDefaultImage\" title=\"Seeadler Chobe Riverfront\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4773 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-10-28 15:46:41\" data-filename=\"IMG_9923-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_9923-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-4757 slide-4773 msDefaultImage\" title=\"Kudu M\u00e4nnchen\" \/><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div><\/div><\/div><\/div><div id=\"pgc-1267-2-1\"  class=\"panel-grid-cell\" ><div class=\"panel-cell-style panel-cell-style-for-1267-2-1\" ><div id=\"panel-1267-2-1-0\" class=\"so-panel widget widget_sow-image panel-first-child\" data-index=\"5\" ><div class=\"panel-widget-style panel-widget-style-for-1267-2-1-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-dbf295114b96-1267\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8603-scaled.jpg\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8603-scaled.jpg 2560w, https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8603-300x225.jpg 300w, https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8603-1024x768.jpg 1024w, https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8603-768x576.jpg 768w, https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8603-1536x1152.jpg 1536w, https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8603-2048x1536.jpg 2048w, https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8603-scaled-1124x844.jpg 1124w, https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8603-scaled-562x422.jpg 562w, https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8603-scaled-728x546.jpg 728w, https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8603-scaled-364x273.jpg 364w, https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8603-scaled-520x390.jpg 520w, https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/IMG_8603-scaled-260x195.jpg 260w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" title=\"IMG_8603\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><div id=\"panel-1267-2-1-1\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"6\" ><div class=\"panel-widget-style panel-widget-style-for-1267-2-1-1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong>Tour operator:<br \/><\/strong>Experiences with Moments Pty Ltd<br \/>Plott 524, Mophane Avenue<br \/>Maun, Botswana<\/p>\n<p>&nbsp;<\/p>\n<p>Telefono: +49 (0)3644 515190<br \/>Cellulare: +49 (0)171 7932630 \/ +49 (0)162 9471783<br \/><a href=\"mailto:info@moments-botswana.com\">info@moments-botswana.com<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Ci riserviamo il diritto di apportare modifiche all'itinerario e agli hotel.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Venite con noi in un viaggio pieno di bei momenti! Parliamo del tuo viaggio.Saremo lieti di sentirti. Nome e-mail Numero di telefono Il vostro messaggio per noi Inviare Tour operator:Experiences with Moments Pty LtdPlott 524, Mophane AvenueMaun, Botswana &nbsp; Telefono: +49 (0)3644 515190Cellulare: +49 (0)171 7932630 \/ +49 (0)162 9471783info@moments-botswana.com &nbsp; Ci riserviamo il diritto di apportare modifiche all&#8217;itinerario e agli hotel.<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-fullwidth.php","meta":{"kt_blocks_editor_width":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","pgc_sgb_lightbox_settings":"","footnotes":""},"class_list":["post-1267","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contattateci - Moments Botswana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/moments-botswana.com\/it\/contattateci\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contattateci - Moments Botswana\" \/>\n<meta property=\"og:description\" content=\"Venite con noi in un viaggio pieno di bei momenti! Parliamo del tuo viaggio.Saremo lieti di sentirti. Nome e-mail Numero di telefono Il vostro messaggio per noi Inviare Tour operator:Experiences with Moments Pty LtdPlott 524, Mophane AvenueMaun, Botswana &nbsp; Telefono: +49 (0)3644 515190Cellulare: +49 (0)171 7932630 \/ +49 (0)162 9471783info@moments-botswana.com &nbsp; Ci riserviamo il diritto di apportare modifiche all&#039;itinerario e agli hotel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/moments-botswana.com\/it\/contattateci\/\" \/>\n<meta property=\"og:site_name\" content=\"Moments Botswana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61555182794338\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-04T06:16:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/moments-botswana.com\\\/it\\\/contattateci\\\/\",\"url\":\"https:\\\/\\\/moments-botswana.com\\\/it\\\/contattateci\\\/\",\"name\":\"Contattateci - Moments Botswana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/moments-botswana.com\\\/it\\\/#website\"},\"datePublished\":\"2024-01-12T06:37:07+00:00\",\"dateModified\":\"2026-02-04T06:16:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/moments-botswana.com\\\/it\\\/contattateci\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/moments-botswana.com\\\/it\\\/contattateci\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/moments-botswana.com\\\/it\\\/contattateci\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/moments-botswana.com\\\/it\\\/safari-di-lusso-in-botswana-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contattateci\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/moments-botswana.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/moments-botswana.com\\\/it\\\/\",\"name\":\"Moments Botswana\",\"description\":\"Luxus Safarireisen in Botswana von Moments by Moments\",\"publisher\":{\"@id\":\"https:\\\/\\\/moments-botswana.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/moments-botswana.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/moments-botswana.com\\\/it\\\/#organization\",\"name\":\"Moments by moments\",\"url\":\"https:\\\/\\\/moments-botswana.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/moments-botswana.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/moments-botswana.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/moments-botswana_logo_HiRes.png\",\"contentUrl\":\"https:\\\/\\\/moments-botswana.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/moments-botswana_logo_HiRes.png\",\"width\":1794,\"height\":643,\"caption\":\"Moments by moments\"},\"image\":{\"@id\":\"https:\\\/\\\/moments-botswana.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61555182794338\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contattateci - Moments Botswana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/moments-botswana.com\/it\/contattateci\/","og_locale":"it_IT","og_type":"article","og_title":"Contattateci - Moments Botswana","og_description":"Venite con noi in un viaggio pieno di bei momenti! Parliamo del tuo viaggio.Saremo lieti di sentirti. Nome e-mail Numero di telefono Il vostro messaggio per noi Inviare Tour operator:Experiences with Moments Pty LtdPlott 524, Mophane AvenueMaun, Botswana &nbsp; Telefono: +49 (0)3644 515190Cellulare: +49 (0)171 7932630 \/ +49 (0)162 9471783info@moments-botswana.com &nbsp; Ci riserviamo il diritto di apportare modifiche all'itinerario e agli hotel.","og_url":"https:\/\/moments-botswana.com\/it\/contattateci\/","og_site_name":"Moments Botswana","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61555182794338","article_modified_time":"2026-02-04T06:16:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/moments-botswana.com\/it\/contattateci\/","url":"https:\/\/moments-botswana.com\/it\/contattateci\/","name":"Contattateci - Moments Botswana","isPartOf":{"@id":"https:\/\/moments-botswana.com\/it\/#website"},"datePublished":"2024-01-12T06:37:07+00:00","dateModified":"2026-02-04T06:16:47+00:00","breadcrumb":{"@id":"https:\/\/moments-botswana.com\/it\/contattateci\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/moments-botswana.com\/it\/contattateci\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/moments-botswana.com\/it\/contattateci\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/moments-botswana.com\/it\/safari-di-lusso-in-botswana-2\/"},{"@type":"ListItem","position":2,"name":"Contattateci"}]},{"@type":"WebSite","@id":"https:\/\/moments-botswana.com\/it\/#website","url":"https:\/\/moments-botswana.com\/it\/","name":"Moments Botswana","description":"Luxus Safarireisen in Botswana von Moments by Moments","publisher":{"@id":"https:\/\/moments-botswana.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/moments-botswana.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/moments-botswana.com\/it\/#organization","name":"Moments by moments","url":"https:\/\/moments-botswana.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/moments-botswana.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/moments-botswana_logo_HiRes.png","contentUrl":"https:\/\/moments-botswana.com\/wp-content\/uploads\/2024\/01\/moments-botswana_logo_HiRes.png","width":1794,"height":643,"caption":"Moments by moments"},"image":{"@id":"https:\/\/moments-botswana.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61555182794338"]}]}},"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"Holger Spreda","author_link":"https:\/\/moments-botswana.com\/it\/author\/holger-spreda\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/moments-botswana.com\/it\/wp-json\/wp\/v2\/pages\/1267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moments-botswana.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/moments-botswana.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/moments-botswana.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/moments-botswana.com\/it\/wp-json\/wp\/v2\/comments?post=1267"}],"version-history":[{"count":0,"href":"https:\/\/moments-botswana.com\/it\/wp-json\/wp\/v2\/pages\/1267\/revisions"}],"wp:attachment":[{"href":"https:\/\/moments-botswana.com\/it\/wp-json\/wp\/v2\/media?parent=1267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}